{"id":24828,"date":"2024-11-27T09:41:29","date_gmt":"2024-11-27T07:41:29","guid":{"rendered":"https:\/\/aedyr.com\/newsletter\/el-gobierno-de-canarias-invertira-23-millones-de-euros-en-la-ampliacion-de-la-capacidad-de-produccion-de-las-desaladoras-de-los-cangrejos-y-la-restinga-ambas-ubicadas-en-la-isla-de-el-hierro\/"},"modified":"2024-11-27T09:51:27","modified_gmt":"2024-11-27T07:51:27","slug":"el-gobierno-de-canarias-invertira-23-millones-de-euros-en-la-ampliacion-de-la-capacidad-de-produccion-de-las-desaladoras-de-los-cangrejos-y-la-restinga-ambas-ubicadas-en-la-isla-de-el-hierro","status":"publish","type":"newsletter","link":"https:\/\/aedyr.com\/en\/newsletter\/el-gobierno-de-canarias-invertira-23-millones-de-euros-en-la-ampliacion-de-la-capacidad-de-produccion-de-las-desaladoras-de-los-cangrejos-y-la-restinga-ambas-ubicadas-en-la-isla-de-el-hierro\/","title":{"rendered":"The Canary Islands Government will invest 2.3 million euros to increase the production capacity of the Los Cangrejos and La Restinga desalination plants, both located on the island of El Hierro"},"content":{"rendered":"","protected":false},"featured_media":0,"parent":0,"template":"","newsletter_cat":[6067],"class_list":["post-24828","newsletter","type-newsletter","status-publish","hentry","newsletter_cat-november-2024"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>The Canary Islands Government will invest 2.3 million euros to increase the production capacity of the Los Cangrejos and La Restinga desalination plants, both located on the island of El Hierro - AEDyR<\/title>\n<meta name=\"description\" content=\"Si quieres estar al d\u00eda en un s\u00f3lo click de la actualidad del sector de la desalaci\u00f3n y reutilizaci\u00f3n de agua, no te puedes perder la Newsletter mensual de AEDyR.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aedyr.com\/en\/newsletter\/el-gobierno-de-canarias-invertira-23-millones-de-euros-en-la-ampliacion-de-la-capacidad-de-produccion-de-las-desaladoras-de-los-cangrejos-y-la-restinga-ambas-ubicadas-en-la-isla-de-el-hierro\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Canary Islands Government will invest 2.3 million euros to increase the production capacity of the Los Cangrejos and La Restinga desalination plants, both located on the island of El Hierro - AEDyR\" \/>\n<meta property=\"og:description\" content=\"Si quieres estar al d\u00eda en un s\u00f3lo click de la actualidad del sector de la desalaci\u00f3n y reutilizaci\u00f3n de agua, no te puedes perder la Newsletter mensual de AEDyR.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aedyr.com\/en\/newsletter\/el-gobierno-de-canarias-invertira-23-millones-de-euros-en-la-ampliacion-de-la-capacidad-de-produccion-de-las-desaladoras-de-los-cangrejos-y-la-restinga-ambas-ubicadas-en-la-isla-de-el-hierro\/\" \/>\n<meta property=\"og:site_name\" content=\"AEDyR\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-27T07:51:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AEDyR_es\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aedyr.com\/en\/newsletter\/el-gobierno-de-canarias-invertira-23-millones-de-euros-en-la-ampliacion-de-la-capacidad-de-produccion-de-las-desaladoras-de-los-cangrejos-y-la-restinga-ambas-ubicadas-en-la-isla-de-el-hierro\/\",\"url\":\"https:\/\/aedyr.com\/en\/newsletter\/el-gobierno-de-canarias-invertira-23-millones-de-euros-en-la-ampliacion-de-la-capacidad-de-produccion-de-las-desaladoras-de-los-cangrejos-y-la-restinga-ambas-ubicadas-en-la-isla-de-el-hierro\/\",\"name\":\"The Canary Islands Government will invest 2.3 million euros to increase the production capacity of the Los Cangrejos and La Restinga desalination plants, both located on the island of El Hierro - AEDyR\",\"isPartOf\":{\"@id\":\"https:\/\/aedyr.com\/#website\"},\"datePublished\":\"2024-11-27T07:41:29+00:00\",\"dateModified\":\"2024-11-27T07:51:27+00:00\",\"description\":\"Si quieres estar al d\u00eda en un s\u00f3lo click de la actualidad del sector de la desalaci\u00f3n y reutilizaci\u00f3n de agua, no te puedes perder la Newsletter mensual de AEDyR.\",\"breadcrumb\":{\"@id\":\"https:\/\/aedyr.com\/en\/newsletter\/el-gobierno-de-canarias-invertira-23-millones-de-euros-en-la-ampliacion-de-la-capacidad-de-produccion-de-las-desaladoras-de-los-cangrejos-y-la-restinga-ambas-ubicadas-en-la-isla-de-el-hierro\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/aedyr.com\/en\/newsletter\/el-gobierno-de-canarias-invertira-23-millones-de-euros-en-la-ampliacion-de-la-capacidad-de-produccion-de-las-desaladoras-de-los-cangrejos-y-la-restinga-ambas-ubicadas-en-la-isla-de-el-hierro\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/aedyr.com\/en\/newsletter\/el-gobierno-de-canarias-invertira-23-millones-de-euros-en-la-ampliacion-de-la-capacidad-de-produccion-de-las-desaladoras-de-los-cangrejos-y-la-restinga-ambas-ubicadas-en-la-isla-de-el-hierro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/aedyr.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Canary Islands Government will invest 2.3 million euros to increase the production capacity of the Los Cangrejos and La Restinga desalination plants, both located on the island of El Hierro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aedyr.com\/#website\",\"url\":\"https:\/\/aedyr.com\/\",\"name\":\"AEDyR\",\"description\":\"Asociaci\u00f3n Espa\u00f1ola de Desalaci\u00f3n y Reutilizaci\u00f3n\",\"publisher\":{\"@id\":\"https:\/\/aedyr.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/aedyr.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/aedyr.com\/#organization\",\"name\":\"Asociaci\u00f3n Espa\u00f1ola de Desalaci\u00f3n y Reutilizaci\u00f3n de Agua (AEDyR)\",\"url\":\"https:\/\/aedyr.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/aedyr.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/aedyr.com\/wp-content\/uploads\/2020\/05\/Logo-aedyr@2x-1.png\",\"contentUrl\":\"https:\/\/aedyr.com\/wp-content\/uploads\/2020\/05\/Logo-aedyr@2x-1.png\",\"width\":1218,\"height\":572,\"caption\":\"Asociaci\u00f3n Espa\u00f1ola de Desalaci\u00f3n y Reutilizaci\u00f3n de Agua (AEDyR)\"},\"image\":{\"@id\":\"https:\/\/aedyr.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/AEDyR_es\",\"https:\/\/www.instagram.com\/aedyr_asociacion\/\",\"https:\/\/www.linkedin.com\/company\/aedyr-es\/\",\"https:\/\/www.youtube.com\/user\/AEDyR\",\"https:\/\/es.wikipedia.org\/wiki\/Asociaci\u00f3n_Espa\u00f1ola_de_Desalaci\u00f3n_y_Reutilizaci\u00f3n\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Canary Islands Government will invest 2.3 million euros to increase the production capacity of the Los Cangrejos and La Restinga desalination plants, both located on the island of El Hierro - AEDyR","description":"Si quieres estar al d\u00eda en un s\u00f3lo click de la actualidad del sector de la desalaci\u00f3n y reutilizaci\u00f3n de agua, no te puedes perder la Newsletter mensual de AEDyR.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aedyr.com\/en\/newsletter\/el-gobierno-de-canarias-invertira-23-millones-de-euros-en-la-ampliacion-de-la-capacidad-de-produccion-de-las-desaladoras-de-los-cangrejos-y-la-restinga-ambas-ubicadas-en-la-isla-de-el-hierro\/","og_locale":"en_US","og_type":"article","og_title":"The Canary Islands Government will invest 2.3 million euros to increase the production capacity of the Los Cangrejos and La Restinga desalination plants, both located on the island of El Hierro - AEDyR","og_description":"Si quieres estar al d\u00eda en un s\u00f3lo click de la actualidad del sector de la desalaci\u00f3n y reutilizaci\u00f3n de agua, no te puedes perder la Newsletter mensual de AEDyR.","og_url":"https:\/\/aedyr.com\/en\/newsletter\/el-gobierno-de-canarias-invertira-23-millones-de-euros-en-la-ampliacion-de-la-capacidad-de-produccion-de-las-desaladoras-de-los-cangrejos-y-la-restinga-ambas-ubicadas-en-la-isla-de-el-hierro\/","og_site_name":"AEDyR","article_modified_time":"2024-11-27T07:51:27+00:00","twitter_card":"summary_large_image","twitter_site":"@AEDyR_es","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aedyr.com\/en\/newsletter\/el-gobierno-de-canarias-invertira-23-millones-de-euros-en-la-ampliacion-de-la-capacidad-de-produccion-de-las-desaladoras-de-los-cangrejos-y-la-restinga-ambas-ubicadas-en-la-isla-de-el-hierro\/","url":"https:\/\/aedyr.com\/en\/newsletter\/el-gobierno-de-canarias-invertira-23-millones-de-euros-en-la-ampliacion-de-la-capacidad-de-produccion-de-las-desaladoras-de-los-cangrejos-y-la-restinga-ambas-ubicadas-en-la-isla-de-el-hierro\/","name":"The Canary Islands Government will invest 2.3 million euros to increase the production capacity of the Los Cangrejos and La Restinga desalination plants, both located on the island of El Hierro - AEDyR","isPartOf":{"@id":"https:\/\/aedyr.com\/#website"},"datePublished":"2024-11-27T07:41:29+00:00","dateModified":"2024-11-27T07:51:27+00:00","description":"Si quieres estar al d\u00eda en un s\u00f3lo click de la actualidad del sector de la desalaci\u00f3n y reutilizaci\u00f3n de agua, no te puedes perder la Newsletter mensual de AEDyR.","breadcrumb":{"@id":"https:\/\/aedyr.com\/en\/newsletter\/el-gobierno-de-canarias-invertira-23-millones-de-euros-en-la-ampliacion-de-la-capacidad-de-produccion-de-las-desaladoras-de-los-cangrejos-y-la-restinga-ambas-ubicadas-en-la-isla-de-el-hierro\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aedyr.com\/en\/newsletter\/el-gobierno-de-canarias-invertira-23-millones-de-euros-en-la-ampliacion-de-la-capacidad-de-produccion-de-las-desaladoras-de-los-cangrejos-y-la-restinga-ambas-ubicadas-en-la-isla-de-el-hierro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/aedyr.com\/en\/newsletter\/el-gobierno-de-canarias-invertira-23-millones-de-euros-en-la-ampliacion-de-la-capacidad-de-produccion-de-las-desaladoras-de-los-cangrejos-y-la-restinga-ambas-ubicadas-en-la-isla-de-el-hierro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/aedyr.com\/en\/"},{"@type":"ListItem","position":2,"name":"The Canary Islands Government will invest 2.3 million euros to increase the production capacity of the Los Cangrejos and La Restinga desalination plants, both located on the island of El Hierro"}]},{"@type":"WebSite","@id":"https:\/\/aedyr.com\/#website","url":"https:\/\/aedyr.com\/","name":"AEDyR","description":"Asociaci\u00f3n Espa\u00f1ola de Desalaci\u00f3n y Reutilizaci\u00f3n","publisher":{"@id":"https:\/\/aedyr.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aedyr.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/aedyr.com\/#organization","name":"Asociaci\u00f3n Espa\u00f1ola de Desalaci\u00f3n y Reutilizaci\u00f3n de Agua (AEDyR)","url":"https:\/\/aedyr.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aedyr.com\/#\/schema\/logo\/image\/","url":"https:\/\/aedyr.com\/wp-content\/uploads\/2020\/05\/Logo-aedyr@2x-1.png","contentUrl":"https:\/\/aedyr.com\/wp-content\/uploads\/2020\/05\/Logo-aedyr@2x-1.png","width":1218,"height":572,"caption":"Asociaci\u00f3n Espa\u00f1ola de Desalaci\u00f3n y Reutilizaci\u00f3n de Agua (AEDyR)"},"image":{"@id":"https:\/\/aedyr.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/AEDyR_es","https:\/\/www.instagram.com\/aedyr_asociacion\/","https:\/\/www.linkedin.com\/company\/aedyr-es\/","https:\/\/www.youtube.com\/user\/AEDyR","https:\/\/es.wikipedia.org\/wiki\/Asociaci\u00f3n_Espa\u00f1ola_de_Desalaci\u00f3n_y_Reutilizaci\u00f3n"]}]}},"_links":{"self":[{"href":"https:\/\/aedyr.com\/en\/wp-json\/wp\/v2\/newsletter\/24828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aedyr.com\/en\/wp-json\/wp\/v2\/newsletter"}],"about":[{"href":"https:\/\/aedyr.com\/en\/wp-json\/wp\/v2\/types\/newsletter"}],"wp:attachment":[{"href":"https:\/\/aedyr.com\/en\/wp-json\/wp\/v2\/media?parent=24828"}],"wp:term":[{"taxonomy":"newsletter_cat","embeddable":true,"href":"https:\/\/aedyr.com\/en\/wp-json\/wp\/v2\/newsletter_cat?post=24828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}